{"id":277,"date":"2023-04-26T18:33:49","date_gmt":"2023-04-26T18:33:49","guid":{"rendered":"https:\/\/mariaperfecta.com\/?page_id=277"},"modified":"2025-01-28T17:49:07","modified_gmt":"2025-01-28T17:49:07","slug":"terminos-del-servicio","status":"publish","type":"page","link":"https:\/\/mariaperfecta.com\/index.php\/terminos-del-servicio\/","title":{"rendered":"T\u00e9rminos del Servicio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"277\" class=\"elementor elementor-277\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c315a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c315a3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bd8c6af\" data-id=\"bd8c6af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b3ac52c\" data-id=\"b3ac52c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a1320d5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a1320d5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-457d50a\" data-id=\"457d50a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef86001 elementor-widget elementor-widget-heading\" data-id=\"ef86001\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00e9rminos de Servicio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-537393f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"537393f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff7d648 elementor-widget elementor-widget-text-editor\" data-id=\"ff7d648\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Maria Perfecta es el operador de Maria Perfecta (\u00abmariaperfecta.com\u00bb). Al realizar un pedido a trav\u00e9s de este sitio web, estar\u00e1 aceptando los t\u00e9rminos a continuaci\u00f3n. Estos se proporcionan para garantizar que ambas partes conozcan y est\u00e9n de acuerdo con este acuerdo para protegerse mutuamente y establecer expectativas sobre nuestro servicio.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-538f61f elementor-widget elementor-widget-text-editor\" data-id=\"538f61f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>VISI\u00d3N GENERAL<\/strong><br \/>Este sitio web es operado por Maria Perfecta. En todo el sitio, los t\u00e9rminos \u00abnosotros\u00bb, \u00abnos\u00bb y \u00abnuestro\u00bb se refieren a Maria Perfecta. Maria Perfecta ofrece este sitio web, incluida toda la informaci\u00f3n, herramientas y servicios disponibles en este sitio para usted, el usuario, est\u00e1 condicionado a la aceptaci\u00f3n de todos los t\u00e9rminos, condiciones, pol\u00edticas y notificaciones aqu\u00ed establecidos.<\/p><p>Al visitar nuestro sitio y \/ o comprarnos algo, participa en nuestro \u00abServicio\u00bb y acepta estar sujeto a los siguientes t\u00e9rminos y condiciones (\u00abT\u00e9rminos de servicio\u00bb, \u00abT\u00e9rminos\u00bb), incluidos los t\u00e9rminos y condiciones y pol\u00edticas adicionales. referenciado en este documento y \/ o disponible por hiperv\u00ednculo. Estos T\u00e9rminos de servicio se aplican a todos los usuarios del sitio, incluidos, entre otros, los usuarios que son navegadores, proveedores, clientes, comerciantes y \/ o contribuyentes de contenido.<\/p><p>Lea estos T\u00e9rminos de servicio detenidamente antes de acceder o utilizar nuestro sitio web. Al acceder o utilizar cualquier parte del sitio, acepta estar sujeto a estos T\u00e9rminos de servicio. Si no est\u00e1 de acuerdo con todos los t\u00e9rminos y condiciones de este acuerdo, no podr\u00e1 acceder al sitio web ni utilizar ning\u00fan servicio. Si estos T\u00e9rminos de servicio se consideran una oferta, la aceptaci\u00f3n se limita expresamente a estos T\u00e9rminos de servicio.<\/p><p>Cualquier caracter\u00edstica o herramienta nueva que se agregue a la tienda actual tambi\u00e9n estar\u00e1 sujeta a los T\u00e9rminos de servicio. Puede revisar la versi\u00f3n m\u00e1s actualizada de los T\u00e9rminos de servicio en cualquier momento en esta p\u00e1gina. Nos reservamos el derecho de actualizar, cambiar o reemplazar cualquier parte de estos T\u00e9rminos de servicio mediante la publicaci\u00f3n de actualizaciones y \/ o cambios en nuestro sitio web. Es su responsabilidad revisar esta p\u00e1gina peri\u00f3dicamente para ver si hay cambios. Su uso continuo o acceso al sitio web despu\u00e9s de la publicaci\u00f3n de cualquier cambio constituye la aceptaci\u00f3n de dichos cambios.<\/p><p>Nuestra tienda est\u00e1 alojada en woocommerce.com\/es\/\u00a0 . Ellos nos proporcionan la plataforma de comercio electr\u00f3nico en l\u00ednea que nos permite venderle nuestros productos y servicios.<\/p><p><strong>SECCI\u00d3N 1 &#8211; T\u00c9RMINOS DE LA TIENDA EN L\u00cdNEA<\/strong><br \/>Al aceptar estos T\u00e9rminos de servicio, usted declara que tiene al menos la mayor\u00eda de edad en su estado o provincia de residencia, o que tiene la mayor\u00eda de edad en su estado o provincia de residencia y nos ha dado su consentimiento para Permita que cualquiera de sus dependientes menores use este sitio.<br \/>No puede usar nuestros productos para ning\u00fan prop\u00f3sito ilegal o no autorizado ni puede, en el uso del Servicio, violar las leyes de su jurisdicci\u00f3n (incluidas, entre otras, las leyes de derechos de autor).<br \/>No debe transmitir gusanos o virus ni ning\u00fan c\u00f3digo de naturaleza destructiva.<br \/>Un incumplimiento o violaci\u00f3n de cualquiera de los T\u00e9rminos resultar\u00e1 en la terminaci\u00f3n inmediata de sus Servicios.<\/p><p><strong>SECCI\u00d3N 2 &#8211; CONDICIONES GENERALES<\/strong><br \/>Nos reservamos el derecho de rechazar el servicio a cualquier persona por cualquier motivo y en cualquier momento.<br \/>Usted comprende que su contenido (sin incluir la informaci\u00f3n de la tarjeta de cr\u00e9dito) puede transferirse sin cifrar e implicar (a) transmisiones a trav\u00e9s de varias redes; y (b) cambios para ajustarse y adaptarse a los requisitos t\u00e9cnicos de conexi\u00f3n de redes o dispositivos. La informaci\u00f3n de la tarjeta de cr\u00e9dito siempre se cifra durante la transferencia a trav\u00e9s de redes.<br \/>Usted acepta no reproducir, duplicar, copiar, vender, revender o explotar ninguna parte del Servicio, el uso del Servicio o el acceso al Servicio o cualquier contacto en el sitio web a trav\u00e9s del cual se brinda el servicio, sin nuestro permiso expreso por escrito.<\/p><p>Los t\u00edtulos utilizados en este acuerdo se incluyen solo por conveniencia y no limitar\u00e1n ni afectar\u00e1n estos T\u00e9rminos.<\/p><p><strong>SECCI\u00d3N 3 &#8211; EXACTITUD, INTEGRIDAD Y PUNTUALIDAD DE LA INFORMACI\u00d3N<\/strong><br \/>No somos responsables si la informaci\u00f3n disponible en este sitio no es precisa, completa o actual. El material de este sitio se proporciona solo para informaci\u00f3n general y no debe confiarse en \u00e9l ni utilizarse como la \u00fanica base para tomar decisiones sin consultar fuentes de informaci\u00f3n primarias, m\u00e1s precisas, m\u00e1s completas o m\u00e1s oportunas. Cualquier dependencia en el material de este sitio es bajo su propio riesgo.<br \/>Este sitio puede contener cierta informaci\u00f3n hist\u00f3rica. La informaci\u00f3n hist\u00f3rica, necesariamente, no es actual y se proporciona solo para su referencia. Nos reservamos el derecho de modificar el contenido de este sitio en cualquier momento, pero no tenemos la obligaci\u00f3n de actualizar ninguna informaci\u00f3n en nuestro sitio. Acepta que es su responsabilidad controlar los cambios en nuestro sitio.<\/p><p><strong>SECCI\u00d3N 4 &#8211; MODIFICACIONES AL SERVICIO Y PRECIOS<\/strong><br \/>Los precios de nuestros productos est\u00e1n sujetos a cambios sin previo aviso.<br \/>Nos reservamos el derecho en cualquier momento de modificar o descontinuar el Servicio (o cualquier parte o contenido del mismo) sin previo aviso en cualquier momento.<\/p><p>No seremos responsables ante usted ni ante ning\u00fan tercero por ninguna modificaci\u00f3n, cambio de precio, suspensi\u00f3n o interrupci\u00f3n del Servicio.<\/p><p><strong>SECCI\u00d3N 5 &#8211; PRODUCTOS O SERVICIOS (si corresponde)<\/strong><br \/>Ciertos productos o servicios pueden estar disponibles exclusivamente en l\u00ednea a trav\u00e9s del sitio web. Estos productos o servicios pueden tener cantidades limitadas y est\u00e1n sujetos a devoluci\u00f3n o cambio solo de acuerdo con nuestra Pol\u00edtica de Devoluci\u00f3n.<br \/>Hemos hecho todo lo posible para mostrar con la mayor precisi\u00f3n posible los colores e im\u00e1genes de nuestros productos que aparecen en la tienda. No podemos garantizar que la visualizaci\u00f3n de cualquier color en el monitor de su computadora sea precisa.<br \/>Nos reservamos el derecho, pero no estamos obligados, a limitar las ventas de nuestros productos o servicios a cualquier persona, regi\u00f3n geogr\u00e1fica o jurisdicci\u00f3n. Podemos ejercer este derecho caso por caso. Nos reservamos el derecho de limitar las cantidades de cualquier producto o servicio que ofrecemos. Todas las descripciones de los productos o los precios de los productos est\u00e1n sujetos a cambios en cualquier momento sin previo aviso, a nuestra entera discreci\u00f3n. Nos reservamos el derecho de descontinuar cualquier producto en cualquier momento. Cualquier oferta de cualquier producto o servicio realizada en este sitio es nula donde est\u00e9 prohibida.<br \/>No garantizamos que la calidad de cualquier producto, servicio, informaci\u00f3n u otro material comprado u obtenido por usted cumpla con sus expectativas, o que cualquier error en el Servicio ser\u00e1 corregido.<\/p><p><strong>SECCI\u00d3N 6 &#8211; PRECISI\u00d3N DE LA FACTURACI\u00d3N Y LA INFORMACI\u00d3N DE LA CUENTA<\/strong><br \/>Nos reservamos el derecho a rechazar cualquier pedido que realice con nosotros. Podemos, a nuestro exclusivo criterio, limitar o cancelar las cantidades compradas por persona, por hogar o por pedido. Estas restricciones pueden incluir pedidos realizados por o bajo la misma cuenta de cliente, la misma tarjeta de cr\u00e9dito y \/ o pedidos que utilizan la misma direcci\u00f3n de facturaci\u00f3n y \/ o env\u00edo. En el caso de que hagamos un cambio o cancelemos un pedido, podemos intentar notificarlo poni\u00e9ndonos en contacto con el correo electr\u00f3nico y \/ o la direcci\u00f3n de facturaci\u00f3n \/ n\u00famero de tel\u00e9fono proporcionado en el momento en que se realiz\u00f3 el pedido. Nos reservamos el derecho de limitar o prohibir los pedidos que, a nuestro exclusivo criterio, parecen ser realizados por concesionarios, revendedores o distribuidores.<\/p><p>Usted acepta proporcionar informaci\u00f3n de compra y cuenta actual, completa y precisa para todas las compras realizadas en nuestra tienda. Acepta actualizar de inmediato su cuenta y otra informaci\u00f3n, incluida su direcci\u00f3n de correo electr\u00f3nico, n\u00fameros de tarjeta de cr\u00e9dito y fechas de vencimiento, para que podamos completar sus transacciones y comunicarnos con usted seg\u00fan sea necesario.<\/p><p>Para obtener m\u00e1s detalles, consulte nuestra Pol\u00edtica de Devoluciones.<\/p><p><strong>SECCI\u00d3N 7 &#8211; HERRAMIENTAS OPCIONALES<\/strong><br \/>Es posible que le proporcionemos acceso a herramientas de terceros sobre las que no supervisamos ni tenemos control ni entrada.<br \/>Usted reconoce y acepta que proporcionamos acceso a dichas herramientas \u00abtal como est\u00e1n\u00bb y \u00abseg\u00fan est\u00e9n disponibles\u00bb sin garant\u00edas, representaciones o condiciones de ning\u00fan tipo y sin ning\u00fan respaldo. No tendremos ninguna responsabilidad derivada o relacionada con su uso de herramientas opcionales de terceros.<br \/>Cualquier uso que haga de las herramientas opcionales ofrecidas a trav\u00e9s del sitio es bajo su propio riesgo y discreci\u00f3n, y debe asegurarse de estar familiarizado y aprobar los t\u00e9rminos en los que las herramientas son proporcionadas por los proveedores externos relevantes.<br \/>Tambi\u00e9n podemos, en el futuro, ofrecer nuevos servicios y \/ o caracter\u00edsticas a trav\u00e9s del sitio web (incluido el lanzamiento de nuevas herramientas y recursos). Tales nuevas caracter\u00edsticas y \/ o servicios tambi\u00e9n estar\u00e1n sujetos a estos T\u00e9rminos de Servicio.<\/p><p><strong>SECCI\u00d3N 8 &#8211; ENLACES DE TERCEROS<\/strong><br \/>Cierto contenido, productos y servicios disponibles a trav\u00e9s de nuestro Servicio pueden incluir materiales de terceros.<br \/>Los enlaces de terceros en este sitio pueden dirigirlo a sitios web de terceros que no est\u00e1n afiliados a nosotros. No somos responsables de examinar o evaluar el contenido o la precisi\u00f3n y no garantizamos ni tendremos ninguna obligaci\u00f3n o responsabilidad por los materiales o sitios web de terceros, o por cualquier otro material, producto o servicio de terceros.<br \/>No somos responsables de ning\u00fan da\u00f1o o perjuicio relacionado con la compra o el uso de bienes, servicios, recursos, contenido o cualquier otra transacci\u00f3n realizada en relaci\u00f3n con sitios web de terceros. Revise cuidadosamente las pol\u00edticas y pr\u00e1cticas de terceros y aseg\u00farese de comprenderlas antes de realizar cualquier transacci\u00f3n. Las quejas, reclamos, inquietudes o preguntas sobre productos de terceros deben dirigirse al tercero.<\/p><p><strong>SECCI\u00d3N 9 &#8211; COMENTARIOS DE USUARIO, RETROALIMENTACI\u00d3N Y OTROS ENVIOS<\/strong><br \/>Si, a petici\u00f3n nuestra, env\u00eda determinadas presentaciones espec\u00edficas (por ejemplo, participaciones en un concurso) o sin una solicitud nuestra, env\u00eda ideas creativas, sugerencias, propuestas, planes u otros materiales, ya sea en l\u00ednea, por correo electr\u00f3nico, por correo postal o de otro modo. (colectivamente, &#8216;comentarios&#8217;), usted acepta que podemos, en cualquier momento, sin restricciones, editar, copiar, publicar, distribuir, traducir y utilizar en cualquier medio cualquier comentario que nos env\u00ede. No tenemos ni tendremos ninguna obligaci\u00f3n (1) de mantener la confidencialidad de los comentarios; (2) pagar una compensaci\u00f3n por cualquier comentario; o (3) para responder a cualquier comentario.<br \/>Podemos, pero no tenemos la obligaci\u00f3n de, monitorear, editar o eliminar contenido que determinemos, a nuestro exclusivo criterio, que es ilegal, ofensivo, amenazante, calumnioso, difamatorio, pornogr\u00e1fico, obsceno o de otra manera objetable o que viole la propiedad intelectual de cualquier parte o estos T\u00e9rminos de servicio .<br \/>Usted acepta que sus comentarios no violar\u00e1n ning\u00fan derecho de terceros, incluidos los derechos de autor, marcas comerciales, privacidad, personalidad u otro derecho personal o de propiedad. Adem\u00e1s, acepta que sus comentarios no contendr\u00e1n material difamatorio o ilegal, abusivo u obsceno, ni contendr\u00e1n ning\u00fan virus inform\u00e1tico u otro malware que pueda afectar de alguna manera el funcionamiento del Servicio o cualquier sitio web relacionado. No puede utilizar una direcci\u00f3n de correo electr\u00f3nico falsa, pretender ser otra persona que no sea usted mismo o enga\u00f1arnos a nosotros oa terceros en cuanto al origen de los comentarios. Usted es el \u00fanico responsable de los comentarios que haga y de su precisi\u00f3n. No asumimos ninguna responsabilidad por los comentarios publicados por usted o un tercero.<\/p><p><strong>SECCI\u00d3N 10 &#8211; INFORMACI\u00d3N PERSONAL<\/strong><br \/>Su env\u00edo de informaci\u00f3n personal a trav\u00e9s de la tienda se rige por nuestra Pol\u00edtica de privacidad. Para ver nuestra Pol\u00edtica de privacidad.<\/p><p><strong>SECCI\u00d3N 11 &#8211; ERRORES, INEXACTITUDES Y OMISIONES<\/strong><br \/>Ocasionalmente, puede haber informaci\u00f3n en nuestro sitio o en el Servicio que contenga errores tipogr\u00e1ficos, inexactitudes u omisiones que puedan estar relacionadas con descripciones de productos, precios, promociones, ofertas, cargos de env\u00edo de productos, tiempos de tr\u00e1nsito y disponibilidad. Nos reservamos el derecho de corregir cualquier error, inexactitud u omisi\u00f3n, y de cambiar o actualizar la informaci\u00f3n o cancelar pedidos si alguna informaci\u00f3n en el Servicio o en cualquier sitio web relacionado es inexacta en cualquier momento sin previo aviso (incluso despu\u00e9s de que haya enviado su pedido).\u00a0<br \/>No asumimos ninguna obligaci\u00f3n de actualizar, modificar o aclarar la informaci\u00f3n en el Servicio o en cualquier sitio web relacionado, incluida, entre otros, la informaci\u00f3n de precios, excepto seg\u00fan lo exija la ley. No se debe tomar ninguna actualizaci\u00f3n espec\u00edfica o fecha de actualizaci\u00f3n aplicada en el Servicio o en cualquier sitio web relacionado para indicar que toda la informaci\u00f3n en el Servicio o en cualquier sitio web relacionado ha sido modificada o actualizada.<\/p><p><strong>SECCI\u00d3N 12 &#8211; USOS PROHIBIDOS<\/strong><br \/>Adem\u00e1s de otras prohibiciones establecidas en los T\u00e9rminos de servicio, tiene prohibido usar el sitio o su contenido: (a) para cualquier prop\u00f3sito ilegal; (b) solicitar a otros que realicen o participen en actos il\u00edcitos; (c) violar cualquier reglamento, regla, ley u ordenanza local internacional, federal, provincial o estatal; (d) infringir o violar nuestros derechos de propiedad intelectual o los derechos de propiedad intelectual de terceros; (e) acosar, abusar, insultar, da\u00f1ar, difamar, calumniar, menospreciar, intimidar o discriminar por motivos de g\u00e9nero, orientaci\u00f3n sexual, religi\u00f3n, etnia, raza, edad, nacionalidad o discapacidad; (f) enviar informaci\u00f3n falsa o enga\u00f1osa; (g) cargar o transmitir virus o cualquier otro tipo de c\u00f3digo malintencionado que se utilizar\u00e1 o se podr\u00e1 utilizar de cualquier forma que afecte la funcionalidad o el funcionamiento del Servicio o de cualquier sitio web relacionado, otros sitios web o Internet; (h) para recopilar o rastrear la informaci\u00f3n personal de otros; (i) enviar spam, phishing, pharm, pretext, spider, crawl o scrape; (j) para cualquier prop\u00f3sito obsceno o inmoral; o (k) para interferir o eludir las caracter\u00edsticas de seguridad del Servicio o cualquier sitio web relacionado, otros sitios web o Internet. Nos reservamos el derecho de terminar su uso del Servicio o cualquier sitio web relacionado por violar cualquiera de los usos prohibidos.<\/p><p><strong>SECCI\u00d3N 13 &#8211; RENUNCIA DE GARANT\u00cdAS; LIMITACI\u00d3N DE RESPONSABILIDAD<\/strong><br \/>No garantizamos, representamos ni garantizamos que su uso de nuestro servicio sea ininterrumpido, oportuno, seguro o libre de errores.<br \/>No garantizamos que los resultados que puedan obtenerse del uso del servicio sean precisos o confiables.<br \/>Usted acepta que de vez en cuando podemos eliminar el servicio por per\u00edodos de tiempo indefinidos o cancelar el servicio en cualquier momento, sin previo aviso.<br \/>Usted acepta expresamente que el uso o la imposibilidad de usar el servicio es bajo su propio riesgo. El servicio y todos los productos y servicios que se le brindan a trav\u00e9s del servicio se brindan (excepto cuando lo indiquemos expresamente) &#8216;tal como est\u00e1n&#8217; y &#8216;seg\u00fan est\u00e9n disponibles&#8217; para su uso, sin ninguna representaci\u00f3n, garant\u00eda o condici\u00f3n de ning\u00fan tipo, ya sea expresa o impl\u00edcito, incluidas todas las garant\u00edas o condiciones impl\u00edcitas de comerciabilidad, calidad comercial, idoneidad para un prop\u00f3sito particular, durabilidad, t\u00edtulo y no infracci\u00f3n.<br \/>En ning\u00fan caso Maria Perfecta, nuestros directores, funcionarios, empleados, afiliados, agentes, contratistas, pasantes, proveedores, prestadores de servicios o licenciatarios ser\u00e1n responsables de cualquier lesi\u00f3n, p\u00e9rdida, reclamo o cualquier da\u00f1o directo, indirecto, incidental, punitivo, especial. , o da\u00f1os consecuentes de cualquier tipo, incluyendo, sin limitaci\u00f3n, lucro cesante, p\u00e9rdida de ingresos, p\u00e9rdida de ahorros, p\u00e9rdida de datos, costos de reemplazo o cualquier da\u00f1o similar, ya sea por contrato, agravio (incluida negligencia), responsabilidad estricta o de otro tipo, que surja por su uso de cualquiera de los servicios o productos adquiridos usando el servicio, o por cualquier otro reclamo relacionado de alguna manera con su uso del servicio o cualquier producto, incluidos, entre otros, cualquier error u omisi\u00f3n en cualquier contenido, o cualquier p\u00e9rdida o da\u00f1o de cualquier tipo incurrido como resultado del uso del servicio o cualquier contenido (o producto) publicado, transmitido o puesto a disposici\u00f3n a trav\u00e9s del servicio, incluso si se advierte de su posibilidad. Debido a que algunos estados o jurisdicciones no permiten la exclusi\u00f3n o la limitaci\u00f3n de responsabilidad por da\u00f1os consecuentes o incidentales, en dichos estados o jurisdicciones, nuestra responsabilidad se limitar\u00e1 al m\u00e1ximo permitido por la ley.<\/p><p><strong>SECCI\u00d3N 14 &#8211; INDEMNIZACI\u00d3N<\/strong><br \/>Usted acepta indemnizar, defender y eximir de responsabilidad a Maria Perfecta y a nuestra matriz, subsidiarias, afiliadas, socios, funcionarios, directores, agentes, contratistas, licenciantes, proveedores de servicios, subcontratistas, proveedores, pasantes y empleados, indemnes de cualquier reclamo o demanda. incluidos los honorarios razonables de abogados, hechos por cualquier tercero debido a o como resultado de su incumplimiento de estos T\u00e9rminos de servicio o los documentos que incorporan por referencia, o su violaci\u00f3n de cualquier ley o los derechos de un tercero.<\/p><p><strong>SECCI\u00d3N 15 &#8211; DIVISIBILIDAD<\/strong><br \/>En el caso de que se determine que alguna disposici\u00f3n de estos T\u00e9rminos de servicio es ilegal, nula o inaplicable, dicha disposici\u00f3n ser\u00e1, no obstante, ejecutable en la mayor medida permitida por la ley aplicable, y la parte inaplicable se considerar\u00e1 separada de estos T\u00e9rminos de Servicio, tal determinaci\u00f3n no afectar\u00e1 la validez y aplicabilidad de cualquier otra disposici\u00f3n restante.<\/p><p><strong>SECCI\u00d3N 16 &#8211; TERMINACI\u00d3N<\/strong><br \/>Las obligaciones y responsabilidades de las partes incurridas antes de la fecha de terminaci\u00f3n sobrevivir\u00e1n a la terminaci\u00f3n de este acuerdo para todos los prop\u00f3sitos.<br \/>Estos T\u00e9rminos de servicio son efectivos a menos que usted o nosotros los rescindamos. Puede rescindir estos T\u00e9rminos de servicio en cualquier momento notific\u00e1ndonos que ya no desea utilizar nuestros Servicios o cuando deje de utilizar nuestro sitio.<br \/>Si, a nuestro exclusivo criterio, usted no cumple, o sospechamos que no ha cumplido con cualquier t\u00e9rmino o disposici\u00f3n de estos T\u00e9rminos de servicio, tambi\u00e9n podemos rescindir este acuerdo en cualquier momento sin previo aviso y usted seguir\u00e1 siendo responsable de todos los montos adeudados. hasta e incluyendo la fecha de terminaci\u00f3n; y \/ o, en consecuencia, puede denegarle el acceso a nuestros Servicios (o cualquier parte de los mismos).<\/p><p><strong>SECCI\u00d3N 17 &#8211; ACUERDO COMPLETO<\/strong><br \/>El hecho de que no ejerzamos o hagamos cumplir cualquier derecho o disposici\u00f3n de estos T\u00e9rminos de servicio no constituir\u00e1 una renuncia a dicho derecho o disposici\u00f3n.<br \/>Estos T\u00e9rminos de servicio y cualquier pol\u00edtica o regla operativa publicada por nosotros en este sitio o con respecto al Servicio constituyen el acuerdo completo y el entendimiento entre usted y nosotros y rigen su uso del Servicio, reemplazando cualquier acuerdo, comunicaciones y propuestas anteriores o contempor\u00e1neos, ya sea oral o escrito, entre usted y nosotros (incluidas, entre otras, las versiones anteriores de los T\u00e9rminos de servicio).<br \/>Cualquier ambig\u00fcedad en la interpretaci\u00f3n de estos T\u00e9rminos de servicio no se interpretar\u00e1 en contra del grupo de redacci\u00f3n.<\/p><p><strong>SECCI\u00d3N 18 &#8211; LEY APLICABLE<\/strong><br \/>Estos T\u00e9rminos de servicio y cualquier acuerdo separado mediante el cual le proporcionemos Servicios se regir\u00e1n e interpretar\u00e1n de acuerdo con las leyes de los Estados Unidos.<\/p><p><strong>SECCI\u00d3N 19 &#8211; CAMBIOS EN LOS T\u00c9RMINOS DE SERVICIO<\/strong><br \/>Puede revisar la versi\u00f3n m\u00e1s actualizada de los T\u00e9rminos de servicio en cualquier momento en esta p\u00e1gina.<br \/>Nos reservamos el derecho, a nuestro exclusivo criterio, de actualizar, cambiar o reemplazar cualquier parte de estos T\u00e9rminos de servicio mediante la publicaci\u00f3n de actualizaciones y cambios en nuestro sitio web. Es su responsabilidad revisar nuestro sitio web peri\u00f3dicamente para ver si hay cambios. Su uso continuo o acceso a nuestro sitio web o al Servicio despu\u00e9s de la publicaci\u00f3n de cualquier cambio en estos T\u00e9rminos de servicio constituye la aceptaci\u00f3n de dichos cambios.<\/p><p><strong>SECCI\u00d3N 20 &#8211; INFORMACI\u00d3N DE CONTACTO<\/strong><br \/>Las preguntas sobre los T\u00e9rminos de servicio deben enviarse a mariaperfectamiamor@gmail.co<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dec13e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5dec13e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f058f9f e-grid-align-mobile-center elementor-shape-circle elementor-grid-6 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"f058f9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-shrink elementor-repeater-item-fad0e3e\" href=\"https:\/\/www.instagram.com\/mariaperfectamiamor\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-tiktok elementor-animation-shrink elementor-repeater-item-49c949c\" href=\"https:\/\/www.tiktok.com\/@mariaperfecta_\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Tiktok<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-tiktok\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-animation-shrink elementor-repeater-item-6e2661e\" href=\"https:\/\/www.youtube.com\/channel\/UCA2wWCgeDD1zxAqBLGoBDSA\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-animation-shrink elementor-repeater-item-1599248\" href=\"http:\/\/chatwith.io\/s\/573028346125\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-pinterest elementor-animation-shrink elementor-repeater-item-08ff064\" href=\"https:\/\/co.pinterest.com\/MariaPerfecta2\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pinterest<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-pinterest\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>T\u00e9rminos de Servicio Maria Perfecta es el operador de Maria Perfecta (\u00abmariaperfecta.com\u00bb). Al realizar un pedido a trav\u00e9s de este sitio web, estar\u00e1 aceptando los t\u00e9rminos a continuaci\u00f3n. Estos se proporcionan para garantizar que ambas partes conozcan y est\u00e9n de acuerdo con este acuerdo para protegerse mutuamente y establecer expectativas sobre nuestro servicio. VISI\u00d3N GENERALEste [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","_joinchat":[],"footnotes":""},"class_list":["post-277","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e9rminos del Servicio - Maria Perfecta<\/title>\n<meta name=\"description\" content=\"T\u00e9rminos de servicio: Operado por Maria Perfecta. En todo el sitio, los t\u00e9rminos \u00abnosotros\u00bb, \u00abnos\u00bb y \u00abnuestro\u00bb se refieren a Maria Perfecta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mariaperfecta.com\/index.php\/terminos-del-servicio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9rminos de servicio\" \/>\n<meta property=\"og:description\" content=\"T\u00e9rminos de servicio: Operado por Maria Perfecta. En todo el sitio, los t\u00e9rminos \u00abnosotros\u00bb, \u00abnos\u00bb y \u00abnuestro\u00bb se refieren a Maria Perfecta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mariaperfecta.com\/index.php\/terminos-del-servicio\/\" \/>\n<meta property=\"og:site_name\" content=\"Maria Perfecta\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-28T17:49:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"T\u00e9rminos de servicio\" \/>\n<meta name=\"twitter:description\" content=\"T\u00e9rminos de servicio: Operado por Maria Perfecta. En todo el sitio, los t\u00e9rminos \u00abnosotros\u00bb, \u00abnos\u00bb y \u00abnuestro\u00bb se refieren a Maria Perfecta.\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mariaperfecta.com\\\/index.php\\\/terminos-del-servicio\\\/\",\"url\":\"https:\\\/\\\/mariaperfecta.com\\\/index.php\\\/terminos-del-servicio\\\/\",\"name\":\"T\u00e9rminos del Servicio - Maria Perfecta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mariaperfecta.com\\\/#website\"},\"datePublished\":\"2023-04-26T18:33:49+00:00\",\"dateModified\":\"2025-01-28T17:49:07+00:00\",\"description\":\"T\u00e9rminos de servicio: Operado por Maria Perfecta. En todo el sitio, los t\u00e9rminos \u00abnosotros\u00bb, \u00abnos\u00bb y \u00abnuestro\u00bb se refieren a Maria Perfecta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mariaperfecta.com\\\/index.php\\\/terminos-del-servicio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mariaperfecta.com\\\/index.php\\\/terminos-del-servicio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mariaperfecta.com\\\/index.php\\\/terminos-del-servicio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mariaperfecta.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9rminos del Servicio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mariaperfecta.com\\\/#website\",\"url\":\"https:\\\/\\\/mariaperfecta.com\\\/\",\"name\":\"Maria Perfecta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mariaperfecta.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mariaperfecta.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mariaperfecta.com\\\/#organization\",\"name\":\"Maria Perfecta\",\"url\":\"https:\\\/\\\/mariaperfecta.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mariaperfecta.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mariaperfecta.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-LOGO_MP_ABRIL_2024-removebg-preview-1-1.png\",\"contentUrl\":\"https:\\\/\\\/mariaperfecta.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-LOGO_MP_ABRIL_2024-removebg-preview-1-1.png\",\"width\":500,\"height\":500,\"caption\":\"Maria Perfecta\"},\"image\":{\"@id\":\"https:\\\/\\\/mariaperfecta.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9rminos del Servicio - Maria Perfecta","description":"T\u00e9rminos de servicio: Operado por Maria Perfecta. En todo el sitio, los t\u00e9rminos \u00abnosotros\u00bb, \u00abnos\u00bb y \u00abnuestro\u00bb se refieren a Maria Perfecta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mariaperfecta.com\/index.php\/terminos-del-servicio\/","og_locale":"es_ES","og_type":"article","og_title":"T\u00e9rminos de servicio","og_description":"T\u00e9rminos de servicio: Operado por Maria Perfecta. En todo el sitio, los t\u00e9rminos \u00abnosotros\u00bb, \u00abnos\u00bb y \u00abnuestro\u00bb se refieren a Maria Perfecta.","og_url":"https:\/\/mariaperfecta.com\/index.php\/terminos-del-servicio\/","og_site_name":"Maria Perfecta","article_modified_time":"2025-01-28T17:49:07+00:00","twitter_card":"summary_large_image","twitter_title":"T\u00e9rminos de servicio","twitter_description":"T\u00e9rminos de servicio: Operado por Maria Perfecta. En todo el sitio, los t\u00e9rminos \u00abnosotros\u00bb, \u00abnos\u00bb y \u00abnuestro\u00bb se refieren a Maria Perfecta.","twitter_misc":{"Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mariaperfecta.com\/index.php\/terminos-del-servicio\/","url":"https:\/\/mariaperfecta.com\/index.php\/terminos-del-servicio\/","name":"T\u00e9rminos del Servicio - Maria Perfecta","isPartOf":{"@id":"https:\/\/mariaperfecta.com\/#website"},"datePublished":"2023-04-26T18:33:49+00:00","dateModified":"2025-01-28T17:49:07+00:00","description":"T\u00e9rminos de servicio: Operado por Maria Perfecta. En todo el sitio, los t\u00e9rminos \u00abnosotros\u00bb, \u00abnos\u00bb y \u00abnuestro\u00bb se refieren a Maria Perfecta.","breadcrumb":{"@id":"https:\/\/mariaperfecta.com\/index.php\/terminos-del-servicio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mariaperfecta.com\/index.php\/terminos-del-servicio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mariaperfecta.com\/index.php\/terminos-del-servicio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mariaperfecta.com\/"},{"@type":"ListItem","position":2,"name":"T\u00e9rminos del Servicio"}]},{"@type":"WebSite","@id":"https:\/\/mariaperfecta.com\/#website","url":"https:\/\/mariaperfecta.com\/","name":"Maria Perfecta","description":"","publisher":{"@id":"https:\/\/mariaperfecta.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mariaperfecta.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mariaperfecta.com\/#organization","name":"Maria Perfecta","url":"https:\/\/mariaperfecta.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mariaperfecta.com\/#\/schema\/logo\/image\/","url":"https:\/\/mariaperfecta.com\/wp-content\/uploads\/2024\/08\/cropped-LOGO_MP_ABRIL_2024-removebg-preview-1-1.png","contentUrl":"https:\/\/mariaperfecta.com\/wp-content\/uploads\/2024\/08\/cropped-LOGO_MP_ABRIL_2024-removebg-preview-1-1.png","width":500,"height":500,"caption":"Maria Perfecta"},"image":{"@id":"https:\/\/mariaperfecta.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mariaperfecta.com\/index.php\/wp-json\/wp\/v2\/pages\/277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mariaperfecta.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mariaperfecta.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mariaperfecta.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mariaperfecta.com\/index.php\/wp-json\/wp\/v2\/comments?post=277"}],"version-history":[{"count":20,"href":"https:\/\/mariaperfecta.com\/index.php\/wp-json\/wp\/v2\/pages\/277\/revisions"}],"predecessor-version":[{"id":8996,"href":"https:\/\/mariaperfecta.com\/index.php\/wp-json\/wp\/v2\/pages\/277\/revisions\/8996"}],"wp:attachment":[{"href":"https:\/\/mariaperfecta.com\/index.php\/wp-json\/wp\/v2\/media?parent=277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}